{"id":157,"date":"2024-05-23T11:16:02","date_gmt":"2024-05-23T11:16:02","guid":{"rendered":"https:\/\/bofabconveyor.se\/\/?page_id=157"},"modified":"2026-05-18T12:51:49","modified_gmt":"2026-05-18T11:51:49","slug":"rullbanor","status":"publish","type":"page","link":"https:\/\/bofabconveyor.se\/en\/rullbanor\/","title":{"rendered":"Roller conveyors"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-0\"><div class=\"row unequal col-no-gutter no-top-padding no-bottom-padding no-h-padding full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell quad-block-padding\" ><div class=\"column-background background-element\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\" style=\"background-image: url(https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/08\/Bakgrund_svart.png);background-repeat: no-repeat;background-position: center center;background-size: cover;\" data-o_src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/08\/Bakgrund_svart.png\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-xsdn-bg\" style=\"opacity: 0.95;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h1 class=\"h6 text-accent-color text-uppercase\" ><span>Roller conveyors<\/span><\/h1><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h2 text-uppercase\" ><span>Roller conveyors for heavy gods<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1739875457186 text-color-prif-color\"  style=\"margin-top: 15px ;\"><p>If you need to handle heavy goods, our powered roller conveyor Heavy will suit your needs. The Heavy roller conveyor is specifically adapted for handling heavier goods. You can use Heavy when it is required to transport for example heavily loaded EUR pallets, shipping pallets, pallets or drive goods directly onto the rollers.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<\/div><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><span class=\"btn-container\" ><a href=\"#offert\" class=\"custom-link h5 btn-custom-typo font-658784 font-weight-400 text-uppercase no-letterspace border-width-0 text-accent-color btn-icon-right\" title=\"Quotation\">Contact us for quotation<i class=\"fa fa-angle-right\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><span class=\"btn-container\" ><a href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/produktblad-heavy-eng.pdf\" class=\"custom-link h5 btn-custom-typo font-658784 font-weight-400 text-uppercase no-letterspace border-width-0 text-accent-color btn-icon-right\" title=\"Product sheet\" target=\"_blank\">Product sheet<i class=\"fa fa-angle-right\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell single-block-padding\" ><div class=\"column-background background-element\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\" style=\"background-image: url(https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27.jpeg);background-repeat: no-repeat;background-position: center center;background-size: cover;\" data-o_src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27.jpeg\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"uncont\" ><div class=\"empty-space empty-quad\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"empty-space empty-quad\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-1\"><div class=\"row-background background-element\" style=\"opacity: 1;\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-475720-bg\" style=\"opacity: 0.06;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"row col-double-gutter double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 inverted-device-order tablet-hidden mobile-hidden col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-right\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"dummy\" style=\"padding-top: 75.1%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_single-107283\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-150x150.jpeg\" data-lg-size=\"1024-683\"><img decoding=\"async\" class=\"wp-image-167\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-uai-910x683.jpeg\" width=\"910\" height=\"683\" alt=\"rullband-bofab\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-uai-910x683.jpeg 910w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-uai-720x540.jpeg 720w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-left align_left column_parent col-lg-6 col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h3 class=\"h3 text-uppercase\" ><span>Designed to handle heavy goods<\/span><\/h3><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1766050055601 text-color-prif-color\"  style=\"margin-top: 15px ;\"><p>We design our roller conveyors to withstand loads of up to 2 tons\/section. They are manufactured in either steel or stainless steel. The leg stands themselves are made of a steel construction, which is also adjustable in height. And the length of each section we can build is up to 3 meters. But in addition to this, you also have the option of being able to link together more sections of roller conveyors. In other words, you have the option of being able to connect several roller conveyors so that it fits your needs in a functional way. Perfect if you want to expand your production line at a later stage. The actual drive of the roller conveyor takes place via roller to roller with 5\/8\" chain via drive stations, where there is a gear motor that ensures that the goods travel at the appropriate speed.<\/p>\n<p>&nbsp;<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-2\"><div class=\"row col-double-gutter double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-left align_left column_parent col-lg-6 col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h3 class=\"h3 text-uppercase\" ><span>Optional accessories for roller conveyors<\/span><\/h3><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1766050087654 text-color-prif-color\"  style=\"margin-top: 15px ;\"><p>In order for it to be as good as possible, we also have a variety of options for our roller conveyors, such as motor protection, safety switches, sensors, pulse sensors, time\/pace, PLC solutions, metal detectors, magnetic separators, frequency converters, etc. Of course, we can also powder coat your roller conveyor in the desired RAL color. Please see our product sheet for <strong><a href=\"https:\/\/bofabconveyor.se\/\/wp-content\/uploads\/2024\/05\/produktblad-rullbana-heavy-2.pdf\" target=\"_blank\" rel=\"noopener\">Roller conveyors<\/a><\/strong> for more technical specifications.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 inverted-device-order tablet-hidden mobile-hidden col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-right\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_single-127912\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-150x150.jpeg\" data-lg-size=\"1024-785\"><img decoding=\"async\" class=\"wp-image-165\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-uai-1024x768.jpeg\" width=\"1024\" height=\"768\" alt=\"bofab-tillbeh&ouml;r\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-uai-1024x768.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-uai-720x540.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-2\" data-row=\"script-row-unique-2\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-2\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-3\"><div class=\"row-background background-element\" style=\"opacity: 1;\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-475720-bg\" style=\"opacity: 0.06;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"row col-double-gutter double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 inverted-device-order tablet-hidden mobile-hidden col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-right\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-24.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_single-171033\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-24-150x150.jpeg\" data-lg-size=\"1024-699\"><img decoding=\"async\" class=\"wp-image-151\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-24-uai-932x699.jpeg\" width=\"932\" height=\"699\" alt=\"kedja-transport&ouml;r\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-24-uai-932x699.jpeg 932w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-24-uai-720x540.jpeg 720w\" sizes=\"(max-width: 932px) 100vw, 932px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-middle pos-left align_left column_parent col-lg-6 col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h3 class=\"h3 text-uppercase\" ><span>Chain Conveyor and Roller Conveyor system<\/span><\/h3><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1766050110967 text-color-prif-color\"  style=\"margin-top: 15px ;\"><p><span class=\"Apple-converted-space\">\u00a0<\/span>Do you need to transport pallets\/goods in different directions in a production line for it to function with optimal efficiency? Then we propose a system of chain conveyors and roller conveyors. Coupled they work very well together. In short, roller conveyors are best suited for transport with the short side forward. While chain conveyors run the goods best with the long side forward. As a result this means that they work well together in the pallet transfer. In other words, choose a combined conveyor system as it allows you to transport pallets\/goods in different directions smoothly. Without unnecessary manual transfers as for instance by a forklift. To learn more about Bofabs Chain Conveyors <strong><a href=\"https:\/\/bofabconveyor.se\/en\/kedjetransportorer\/\">click here.<span class=\"Apple-converted-space\">\u00a0<\/span><\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-3\" data-row=\"script-row-unique-3\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-3\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-4\"><div class=\"row col-double-gutter double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-left align_left column_parent col-lg-6 col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h5 class=\"h3 text-uppercase\" ><span>Durable and functional roller conveyors<\/span><\/h5><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1767794930288 text-color-prif-color\"  style=\"margin-top: 15px ;\"><p>We create, in collaboration with you, customized solutions. And to be able to ensure the quality and function of our designs, we build our conveyors under our own roof, from the ground up, with best operation and safety in mind. We guarantee you a qualitative and affordable solution.<\/p>\n<p>We have the knowledge you need.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\n<\/div><span class=\"btn-container\" ><a href=\"#offert\" class=\"custom-link h5 btn-custom-typo font-658784 font-weight-400 text-uppercase no-letterspace border-width-0 text-accent-color btn-icon-right\" title=\"Quotation\">Contact us for quotation<i class=\"fa fa-angle-right\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 inverted-device-order tablet-hidden mobile-hidden col-md-50 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-right\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"dummy\" style=\"padding-top: 75.1%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/DSC_8723.jpg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_single-767906\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/DSC_8723-150x150.jpg\" data-lg-size=\"1029-683\"><img decoding=\"async\" class=\"wp-image-697\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/DSC_8723-uai-910x683.jpg\" width=\"910\" height=\"683\" alt=\"bofab-tillverkning\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/DSC_8723-uai-910x683.jpg 910w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/09\/DSC_8723-uai-720x540.jpg 720w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-4\" data-row=\"script-row-unique-4\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-4\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-5\"><div class=\"row-background background-element\" style=\"opacity: 1;\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"background-inner\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-bg-overlay style-color-475720-bg\" style=\"opacity: 0.06;\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"row triple-top-padding triple-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h3 class=\"h2 text-uppercase\" ><span>Pictures<\/span><\/h3><\/div><div class=\"clear\"><\/div><\/div><div id=\"gallery-114657\" class=\"isotope-system isotope-general-light grid-general-light\">\n\t\t\t\t\t\n\t<div class=\"isotope-wrapper grid-wrapper px-gutter\" >\n\t\t\t\t\t\t\t\t\t<div class=\"isotope-container isotope-layout style-masonry\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\">\n<div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-159  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 87%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27-150x150.jpeg\" data-lg-size=\"1024-891\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-159\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27.jpeg\" width=\"1024\" height=\"891\" alt=\"rullband-bofab\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27-300x261.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27-768x668.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27-350x305.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-27-uai-720x626.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-160  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28-150x150.jpeg\" data-lg-size=\"1024-683\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-160\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28.jpeg\" width=\"1024\" height=\"683\" alt=\"rullband\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28-300x200.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28-768x512.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28-350x233.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-28-uai-720x480.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-162  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 76.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29-150x150.jpeg\" data-lg-size=\"1024-785\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-162\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29.jpeg\" width=\"1024\" height=\"785\" alt=\"rullband-bofab\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29-300x230.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29-768x589.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29-350x268.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-29-uai-720x552.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-163  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-150x150.jpeg\" data-lg-size=\"2048-1365\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-163\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30.jpeg\" width=\"2048\" height=\"1365\" alt=\"rullband\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30.jpeg 2048w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-300x200.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-1024x683.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-768x512.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-1536x1024.jpeg 1536w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-350x233.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-uai-720x480.jpeg 720w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-30-uai-1032x688.jpeg 1032w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-164  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-150x150.jpeg\" data-lg-size=\"2048-1365\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-164\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31.jpeg\" width=\"2048\" height=\"1365\" alt=\"rullband-fabrik\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31.jpeg 2048w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-300x200.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-1024x683.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-768x512.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-1536x1024.jpeg 1536w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-350x233.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-uai-720x480.jpeg 720w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-31-uai-1032x688.jpeg 1032w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-165  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 76.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-150x150.jpeg\" data-lg-size=\"1024-785\" data-lb-index=\"5\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-165\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32.jpeg\" width=\"1024\" height=\"785\" alt=\"bofab-tillbeh\u00f6r\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-300x230.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-768x589.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-350x268.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-32-uai-720x552.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-167  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-150x150.jpeg\" data-lg-size=\"1024-683\" data-lb-index=\"6\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-167\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34.jpeg\" width=\"1024\" height=\"683\" alt=\"rullband-bofab\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34.jpeg 1024w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-300x200.jpeg 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-768x512.jpeg 768w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-350x233.jpeg 350w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-34-uai-720x480.jpeg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-168  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 149.9%;\"><\/div><a tabindex=\"-1\" href=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35.jpeg\" class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-114657\" data-external-thumb-image=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35-150x150.jpeg\" data-lg-size=\"683-1024\" data-lb-index=\"7\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-168\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35.jpeg\" width=\"683\" height=\"1024\" alt=\"rullband-rosfritt\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35.jpeg 683w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35-200x300.jpeg 200w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/05\/image-35-350x525.jpeg 350w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\t\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-5\" data-row=\"script-row-unique-5\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-5\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row style-color-xsdn-bg row-container onepage-section\" data-label=\"offert\" data-name=\"offert\" id=\"row-unique-6\"><div class=\"row triple-top-padding triple-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-8 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h5 class=\"h4\" ><span>Contact us today to get a qualitative and affordable solution!<\/span><\/h5><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1726055847737\"  style=\"margin-top: 15px ;\"><p>Bofab\u2019s driven roller conveyor is available for transport of medium and heavy goods. Our roller conveyors are adapted to the need for transport of pallets or goods, for example, directly on the reels.<\/p>\n<p>Interested in learning more? Then feel free to read through our <strong><a href=\"https:\/\/bofabconveyor.se\/en\/produktblad\/\">product sheets<\/a><\/strong> or contact us and we will tell you more about our products.<\/p>\n<\/div><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-653\" src=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/10\/roller-conveyor-heavy.png\" width=\"650\" height=\"300\" alt=\"transport&ouml;r\" srcset=\"https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/10\/roller-conveyor-heavy.png 650w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/10\/roller-conveyor-heavy-300x138.png 300w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/10\/roller-conveyor-heavy-18x8.png 18w, https:\/\/bofabconveyor.se\/wp-content\/uploads\/2024\/10\/roller-conveyor-heavy-350x162.png 350w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f326-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"326\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/157#wpcf7-f326-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/157#wpcf7-f326-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"326\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f326-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-foretag\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company\" value=\"\" type=\"text\" name=\"your-foretag\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-firstname\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Your message\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-accent\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-4 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h5 class=\"h5\" ><span>Petter Fredrikson<\/span><\/h5><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1716971486019\"  style=\"margin-top: 5px ;\"><p>CEO \/ Sales<br \/>\nPhone: +46(0)143-294 82<br \/>\nE-mail: petter@bofab.com<\/p>\n<\/div><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h5 class=\"h5\" ><span>Michael Fredrikson<\/span><\/h5><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column vc_custom_1716971496503\"  style=\"margin-top: 5px ;\"><p>Senior Advisor \/ Sales<br \/>\nPhone: +46(0)143-294 85<br \/>\nE-mail: michael@bofab.com<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-6\" data-row=\"script-row-unique-6\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-6\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"RullbanorRullbanor f\u00f6r tungt godsBeh\u00f6ver du hantera tunga gods s\u00e5 passar v\u00e5r drivna rullbana Heavy dina behov. Rullbanan Heavy \u00e4r n\u00e4mligen [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor<\/title>\n<meta name=\"description\" content=\"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bofabconveyor.se\/en\/rullbanor\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor\" \/>\n<meta property=\"og:description\" content=\"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bofabconveyor.se\/en\/rullbanor\/\" \/>\n<meta property=\"og:site_name\" content=\"Bofab transport\u00f6rsystem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bofabconveyor\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T11:51:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bofabconveyor.se\\\/rullbanor\\\/\",\"url\":\"https:\\\/\\\/bofabconveyor.se\\\/rullbanor\\\/\",\"name\":\"Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bofabconveyor.se\\\/#website\"},\"datePublished\":\"2024-05-23T11:16:02+00:00\",\"dateModified\":\"2026-05-18T11:51:49+00:00\",\"description\":\"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bofabconveyor.se\\\/rullbanor\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bofabconveyor.se\\\/rullbanor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bofabconveyor.se\\\/rullbanor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/bofabconveyor.se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rullbanor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bofabconveyor.se\\\/#website\",\"url\":\"https:\\\/\\\/bofabconveyor.se\\\/\",\"name\":\"Bofab transport\u00f6rsystem\",\"description\":\"Tillverkare av transport\u00f6rer i \u00f6ver 50 \u00e5r\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bofabconveyor.se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor","description":"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bofabconveyor.se\/en\/rullbanor\/","og_locale":"en_GB","og_type":"article","og_title":"Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor","og_description":"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.","og_url":"https:\/\/bofabconveyor.se\/en\/rullbanor\/","og_site_name":"Bofab transport\u00f6rsystem","article_publisher":"https:\/\/www.facebook.com\/bofabconveyor\/","article_modified_time":"2026-05-18T11:51:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bofabconveyor.se\/rullbanor\/","url":"https:\/\/bofabconveyor.se\/rullbanor\/","name":"Rullbanor - F\u00f6r b\u00e5de l\u00e4tt och tungt gods - Bofab Conveyor","isPartOf":{"@id":"https:\/\/bofabconveyor.se\/#website"},"datePublished":"2024-05-23T11:16:02+00:00","dateModified":"2026-05-18T11:51:49+00:00","description":"Rullbanor kan hantera tunga gods effektivt. Vi anpassar transport\u00f6ren efter dina behov, f\u00f6r att optimera hanteringen av tyngre gods.","breadcrumb":{"@id":"https:\/\/bofabconveyor.se\/rullbanor\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bofabconveyor.se\/rullbanor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bofabconveyor.se\/rullbanor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/bofabconveyor.se\/"},{"@type":"ListItem","position":2,"name":"Rullbanor"}]},{"@type":"WebSite","@id":"https:\/\/bofabconveyor.se\/#website","url":"https:\/\/bofabconveyor.se\/","name":"Bofab Conveyor","description":"Tillverkare av transport\u00f6rer i \u00f6ver 50 \u00e5r","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bofabconveyor.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":40,"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":1121,"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/pages\/157\/revisions\/1121"}],"wp:attachment":[{"href":"https:\/\/bofabconveyor.se\/en\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}